{"id":1408,"date":"2021-04-17T13:18:13","date_gmt":"2021-04-17T16:18:13","guid":{"rendered":"https:\/\/marcodastresfronteiras.com.br\/blog\/?p=1408"},"modified":"2021-04-20T17:31:47","modified_gmt":"2021-04-20T20:31:47","slug":"olhar-fotografico-no-marco-das-3-fronteiras","status":"publish","type":"post","link":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/","title":{"rendered":"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras"},"content":{"rendered":"<p style=\"text-align: justify;\">Fotografias de casais e declara\u00e7\u00f5es de amor s\u00e3o sempre fascinantes e super fofas de contemplar. O <a href=\"https:\/\/www.instagram.com\/marco3fronteiras\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marco das 3 Fronteiras<\/a>, lugar mais charmoso de Foz do Igua\u00e7u, \u00e9 um local repleto de hist\u00f3rias envolventes. O atrativo sempre re\u00fane diversos casais, que escolhem dentre v\u00e1rios atrativos da cidade, o Marco para realizar seus ensaios fotogr\u00e1ficos ou discursos apaixonantes.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-1411 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33-300x169.jpeg\" alt=\"\" width=\"905\" height=\"510\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33-300x169.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33-1024x576.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33-768x432.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33.jpeg 1280w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Cr\u00e9ditos fotografias: <a href=\"https:\/\/www.marceloguazzi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo Guazzi<\/a><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">O visitante <a href=\"https:\/\/www.instagram.com\/marceloguazzi\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo Guazzi<\/a>, fot\u00f3grafo da regi\u00e3o, gosta de viver grandes emo\u00e7\u00f5es sempre se identificou em registrar momentos marcantes, como as fotografias de casamentos, carregadas de emo\u00e7\u00f5es. <a href=\"https:\/\/www.instagram.com\/marceloguazzi\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo<\/a> contou os motivos que fazem ele amar registrar celebra\u00e7\u00f5es no <a href=\"https:\/\/www.instagram.com\/marco3fronteiras\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marco das 3 Fronteiras<\/a>. Confira:<\/p>\n<p><img decoding=\"async\" class=\" wp-image-1417 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.34-300x169.jpeg\" alt=\"\" width=\"905\" height=\"510\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.34-300x169.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.34-1024x576.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.34-768x432.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.34.jpeg 1280w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Cr\u00e9ditos fotografias: <a href=\"https:\/\/www.marceloguazzi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo Guazzi<\/a><\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u201cO p\u00f4r do sol nesse local \u00e9 incr\u00edvel e a sua estrutura \u00e9 maravilhosa. O ambiente \u00e9 cheio de hist\u00f3ria e a sua arquitetura repleta de detalhes. Nos leva a um cen\u00e1rio muito bonito, repleto de cores e ambientes bem iluminados, podemos criar fotografias mais art\u00edsticas\u201d<\/em>, contou <a href=\"https:\/\/www.instagram.com\/marceloguazzi\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo<\/a>.<\/p>\n<p><img decoding=\"async\" class=\" wp-image-1415 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_1-300x169.jpeg\" alt=\"\" width=\"905\" height=\"510\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_1-300x169.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_1-1024x576.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_1-768x432.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_1.jpeg 1280w\" sizes=\"(max-width: 905px) 100vw, 905px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Cr\u00e9ditos fotografias: <a href=\"https:\/\/www.marceloguazzi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo Guazzi<\/a><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">N\u00e3o \u00e9 \u00e0 toa, j\u00e1 que a cidade de Foz do Igua\u00e7u est\u00e1 entre os melhores lugares para ver o entardecer: <em>\u201cO p\u00f4r do sol de Foz do Igua\u00e7u est\u00e1 no top 10 do site Skyscanner. Um dos pores do sol mais incr\u00edvel do Brasil, e o Marco das Tr\u00eas Fronteiras \u00e9 um dos lugares mais privilegiados pela localiza\u00e7\u00e3o e beleza, a sua estrutura e a ilumina\u00e7\u00e3o nos proporcionam fotos incr\u00edveis\u201d<\/em>, disse o fot\u00f3grafo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1418 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.39-300x169.jpeg\" alt=\"\" width=\"908\" height=\"511\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.39-300x169.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.39-1024x576.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.39-768x432.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.39.jpeg 1280w\" sizes=\"(max-width: 908px) 100vw, 908px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Cr\u00e9ditos fotografias: <a href=\"https:\/\/www.marceloguazzi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo Guazzi<\/a><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">O Marco \u00e9 palco de lindas declara\u00e7\u00f5es de amor e sempre recebe pedidos especiais: <em>\u201cMuitos dos casais me pedem para fotografar no Marco pela hist\u00f3ria que eles t\u00eam com esse local, muitos pedidos de noivados aconteceram neste lugar\u201d<\/em>, relatou ele.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1413 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.32_1-300x169.jpeg\" alt=\"\" width=\"904\" height=\"509\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.32_1-300x169.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.32_1-1024x576.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.32_1-768x432.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.32_1.jpeg 1280w\" sizes=\"(max-width: 904px) 100vw, 904px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Cr\u00e9ditos fotografias: <a href=\"https:\/\/www.marceloguazzi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo Guazzi<\/a><\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.instagram.com\/marceloguazzi\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marcelo<\/a> contou o processo de fotografar casais e a import\u00e2ncia de cada detalhe: <em>\u201cFotografar casais n\u00e3o \u00e9 apenas marcar um dia e ir fotografar, \u00e9 um processo que come\u00e7a muito antes. N\u00f3s fazemos uma entrevista com eles, afinal precisamos conhecer a hist\u00f3ria deles, \u00e9 preciso ter uma sintonia com o casal, \u00e9 nessa conversa que sentimos a personalidade deles, e eles se sentirem mais \u00e0 vontade comigo\u201d.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-1416 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2-300x169.jpeg\" alt=\"\" width=\"906\" height=\"510\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2-300x169.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2-1024x576.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2-768x432.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg 1280w\" sizes=\"(max-width: 906px) 100vw, 906px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Cr\u00e9ditos fotografias:<a href=\"https:\/\/www.marceloguazzi.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Marcelo Guazzi<\/a><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Programe-se com o seu amor e venha fazer um ensaio fotogr\u00e1fico aqui no <a href=\"https:\/\/www.instagram.com\/marco3fronteiras\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marco das 3 Fronteiras<\/a>! Declara\u00e7\u00f5es e recorda\u00e7\u00f5es apaixonadas s\u00e3o sempre bem-vindas. O atrativo mais charmoso de Foz do Igua\u00e7u est\u00e1 aberto, esperando por voc\u00eas.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Fotografias de casais e declara\u00e7\u00f5es de amor s\u00e3o sempre fascinantes e super fofas de contemplar. O Marco das 3 Fronteiras, lugar mais charmoso de Foz do Igua\u00e7u, \u00e9 um local repleto de hist\u00f3rias envolventes. O atrativo sempre re\u00fane diversos casais, que escolhem dentre v\u00e1rios atrativos da cidade, o Marco para realizar seus ensaios fotogr\u00e1ficos ou [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experiencias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olhar fotogr\u00e1fico no Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras\" \/>\n<meta property=\"og:description\" content=\"Fotografias de casais e declara\u00e7\u00f5es de amor s\u00e3o sempre fascinantes e super fofas de contemplar. O Marco das 3 Fronteiras, lugar mais charmoso de Foz do Igua\u00e7u, \u00e9 um local repleto de hist\u00f3rias envolventes. O atrativo sempre re\u00fane diversos casais, que escolhem dentre v\u00e1rios atrativos da cidade, o Marco para realizar seus ensaios fotogr\u00e1ficos ou [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Oficial do Marco das 3 Fronteiras\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-17T16:18:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-20T20:31:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Parques Rio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Parques Rio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/\"},\"author\":{\"name\":\"Parques Rio\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\"},\"headline\":\"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras\",\"datePublished\":\"2021-04-17T16:18:13+00:00\",\"dateModified\":\"2021-04-20T20:31:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/\"},\"wordCount\":427,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg\",\"articleSection\":[\"Experi\u00eancias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/\",\"name\":\"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg\",\"datePublished\":\"2021-04-17T16:18:13+00:00\",\"dateModified\":\"2021-04-20T20:31:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg\",\"contentUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/olhar-fotografico-no-marco-das-3-fronteiras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/\",\"name\":\"Blog Oficial do Marco das 3 Fronteiras\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\",\"name\":\"Parques Rio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"caption\":\"Parques Rio\"},\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/author\\\/cataratas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/","og_locale":"pt_BR","og_type":"article","og_title":"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras","og_description":"Fotografias de casais e declara\u00e7\u00f5es de amor s\u00e3o sempre fascinantes e super fofas de contemplar. O Marco das 3 Fronteiras, lugar mais charmoso de Foz do Igua\u00e7u, \u00e9 um local repleto de hist\u00f3rias envolventes. O atrativo sempre re\u00fane diversos casais, que escolhem dentre v\u00e1rios atrativos da cidade, o Marco para realizar seus ensaios fotogr\u00e1ficos ou [&hellip;]","og_url":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/","og_site_name":"Blog Oficial do Marco das 3 Fronteiras","article_published_time":"2021-04-17T16:18:13+00:00","article_modified_time":"2021-04-20T20:31:47+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg","type":"image\/jpeg"}],"author":"Parques Rio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Parques Rio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/#article","isPartOf":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/"},"author":{"name":"Parques Rio","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba"},"headline":"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras","datePublished":"2021-04-17T16:18:13+00:00","dateModified":"2021-04-20T20:31:47+00:00","mainEntityOfPage":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/"},"wordCount":427,"commentCount":0,"image":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/#primaryimage"},"thumbnailUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg","articleSection":["Experi\u00eancias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/","name":"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras","isPartOf":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/#primaryimage"},"image":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/#primaryimage"},"thumbnailUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg","datePublished":"2021-04-17T16:18:13+00:00","dateModified":"2021-04-20T20:31:47+00:00","author":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba"},"breadcrumb":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/#primaryimage","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg","contentUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/04\/WhatsApp_Image_2021-04-13_at_15.12.33_2.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/olhar-fotografico-no-marco-das-3-fronteiras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/marcodastresfronteiras.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Olhar fotogr\u00e1fico no Marco das 3 Fronteiras"}]},{"@type":"WebSite","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#website","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/","name":"Blog Oficial do Marco das 3 Fronteiras","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcodastresfronteiras.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba","name":"Parques Rio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","caption":"Parques Rio"},"url":"https:\/\/marcodastresfronteiras.com.br\/blog\/author\/cataratas\/"}]}},"_links":{"self":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts\/1408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1408"}],"version-history":[{"count":0,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts\/1408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/media\/1416"}],"wp:attachment":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}