{"id":1240,"date":"2021-01-21T16:44:54","date_gmt":"2021-01-21T19:44:54","guid":{"rendered":"https:\/\/marcodastresfronteiras.com.br\/blog\/?p=1240"},"modified":"2021-02-01T14:35:16","modified_gmt":"2021-02-01T17:35:16","slug":"moradores-pagam-menos-para-participar-da-meiadascataratas","status":"publish","type":"post","link":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/","title":{"rendered":"Moradores pagam menos para participar da #MeiadasCataratas"},"content":{"rendered":"<p style=\"text-align: justify;\">As inscri\u00e7\u00f5es para a 13\u00aa edi\u00e7\u00e3o da Meia Maratona das Cataratas, uma das provas mais fascinantes do mundo, continuam abertas e com benef\u00edcios especiais aos habitantes das 14 cidades vizinhas ao Parque Nacional do Igua\u00e7u. Ao realizar a inscri\u00e7\u00e3o presencialmente, no Marco das 3 Fronteiras, o morador garante 20% de desconto.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1243 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/IMG_9945-300x200.jpg\" alt=\"\" width=\"803\" height=\"535\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/IMG_9945-300x200.jpg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/IMG_9945-1024x683.jpg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/IMG_9945-768x512.jpg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/IMG_9945-1536x1024.jpg 1536w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/IMG_9945-2048x1365.jpg 2048w\" sizes=\"(max-width: 803px) 100vw, 803px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9ditos fotografia: Nilton Rolin<\/em><\/p>\n<p style=\"text-align: justify;\">A Meia das Cataratas ser\u00e1 realizada no dia 6 de junho, seguindo todos os cuidados para garantir o bem-estar dos participantes. A prova reservar\u00e1 aos corredores momentos \u00fanicos de contempla\u00e7\u00e3o e contato com a natureza do parque, ao ar livre, com a magia das Cataratas do Igua\u00e7u, o maior conjunto de quedas d\u2019\u00e1gua do mundo, no meio do percurso. Imperd\u00edvel, n\u00e3o \u00e9?<\/p>\n<p><img decoding=\"async\" class=\"wp-image-1242 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Creditos-Nilton-Rolin-10-300x200.jpg\" alt=\"\" width=\"803\" height=\"536\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Creditos-Nilton-Rolin-10-300x200.jpg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Creditos-Nilton-Rolin-10-1024x683.jpg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Creditos-Nilton-Rolin-10-768x512.jpg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Creditos-Nilton-Rolin-10-1536x1024.jpg 1536w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Creditos-Nilton-Rolin-10-2048x1365.jpg 2048w\" sizes=\"(max-width: 803px) 100vw, 803px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9ditos fotografia: Nilton Rolin<\/em><\/p>\n<p style=\"text-align: justify;\">Os valores promocionais s\u00e3o destinados a moradores dos 14 munic\u00edpios vizinhos do PNI. S\u00e3o eles: Foz do Igua\u00e7u, Santa Terezinha de Itaipu, S\u00e3o Miguel do Igua\u00e7u, Matel\u00e2ndia, Medianeira, Ramil\u00e2ndia, Santa L\u00facia, Serran\u00f3polis do Igua\u00e7u, Vera Cruz do Oeste, Capanema, Capit\u00e3o Le\u00f4nidas Marques, C\u00e9u Azul, Lindoeste e Santa Tereza do Oeste. A promo\u00e7\u00e3o \u00e9 v\u00e1lida mediante apresenta\u00e7\u00e3o de comprovante de resid\u00eancia e documento com foto.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-1244 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Quedas-Foto-Marcos-Labanca-76-300x200.jpg\" alt=\"\" width=\"805\" height=\"536\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Quedas-Foto-Marcos-Labanca-76-300x200.jpg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Quedas-Foto-Marcos-Labanca-76-1536x1025.jpg 1536w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/Quedas-Foto-Marcos-Labanca-76-2048x1367.jpg 2048w\" sizes=\"(max-width: 805px) 100vw, 805px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9ditos fotografia: Marcos Labanca<\/em><\/p>\n<p style=\"text-align: justify;\">Os interessados poder\u00e3o optar por enviar terceiros para realizar a inscri\u00e7\u00e3o por eles. O emiss\u00e1rio precisar\u00e1 levar os documentos pessoais e comprovante de resid\u00eancia da pessoa a ser inscrita. Os participantes que n\u00e3o conseguirem comprovar moradia em uma das 14 cidades vizinhas ao Parque Nacional do Igua\u00e7u ter\u00e3o de fazer a inscri\u00e7\u00e3o geral no site oficial da prova: <a href=\"http:\/\/www.meiamaratonadascataratas.com.br\/\">www.meiamaratonadascataratas.com.br<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1245 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Roberto-Lemos-108-300x200.jpg\" alt=\"\" width=\"803\" height=\"535\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Roberto-Lemos-108-300x200.jpg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Roberto-Lemos-108-1024x683.jpg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Roberto-Lemos-108-768x512.jpg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Roberto-Lemos-108-1536x1024.jpg 1536w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Roberto-Lemos-108-2048x1365.jpg 2048w\" sizes=\"(max-width: 803px) 100vw, 803px\" \/><\/p>\n<p style=\"text-align: center;\"><em>Cr\u00e9ditos fotografia: Roberto Lemos<\/em><\/p>\n<p><strong>Servi\u00e7o<\/strong><\/p>\n<p><strong>13\u00aa Meia Maratona das Cataratas e Desafio 8 km das Cataratas<\/strong><\/p>\n<p>Data: 6 de junho de 2021 (domingo)<\/p>\n<p>Local: Parque Nacional do Igua\u00e7u \u2013 Foz do Igua\u00e7u<\/p>\n<p><strong>Inscri\u00e7\u00f5es gerais no site da prova:<\/strong><\/p>\n<p><a href=\"http:\/\/www.meiamaratonadascataratas.com.br\">www.meiamaratonadascataratas.com.br<\/a><\/p>\n<p><strong>Central de Atendimento ao Corredor \u2013 WhatsApp<\/strong><\/p>\n<p>+55 (45) 9137-3444 \u2013 <a href=\"https:\/\/wa.me\/5545991373444\">https:\/\/wa.me\/5545991373444<\/a><\/p>\n<p><strong>\u00c1lbum de fotografias da Meia Maratona das Cataratas:<\/strong> <a href=\"https:\/\/flic.kr\/s\/aHsmuSVdbq\">https:\/\/flic.kr\/s\/aHsmuSVdbq<\/a><\/p>\n<p><strong>Acompanhe a #MeiaDasCataratas nas redes sociais:<\/strong><\/p>\n<p>Facebook: www.facebook.com\/MeiadasCataratas<\/p>\n<p>Instagram: www.instagram.com\/MeiaDasCataratas<\/p>\n<p>Twitter: www.twitter.com\/MeiaMaratona<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As inscri\u00e7\u00f5es para a 13\u00aa edi\u00e7\u00e3o da Meia Maratona das Cataratas, uma das provas mais fascinantes do mundo, continuam abertas e com benef\u00edcios especiais aos habitantes das 14 cidades vizinhas ao Parque Nacional do Igua\u00e7u. Ao realizar a inscri\u00e7\u00e3o presencialmente, no Marco das 3 Fronteiras, o morador garante 20% de desconto. Cr\u00e9ditos fotografia: Nilton Rolin [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Moradores pagam menos para participar da #MeiadasCataratas - Blog Oficial do Marco das 3 Fronteiras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moradores pagam menos para participar da #MeiadasCataratas - Blog Oficial do Marco das 3 Fronteiras\" \/>\n<meta property=\"og:description\" content=\"As inscri\u00e7\u00f5es para a 13\u00aa edi\u00e7\u00e3o da Meia Maratona das Cataratas, uma das provas mais fascinantes do mundo, continuam abertas e com benef\u00edcios especiais aos habitantes das 14 cidades vizinhas ao Parque Nacional do Igua\u00e7u. Ao realizar a inscri\u00e7\u00e3o presencialmente, no Marco das 3 Fronteiras, o morador garante 20% de desconto. Cr\u00e9ditos fotografia: Nilton Rolin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Oficial do Marco das 3 Fronteiras\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-21T19:44:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-01T17:35:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1724\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Parques Rio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Parques Rio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/\"},\"author\":{\"name\":\"Parques Rio\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\"},\"headline\":\"Moradores pagam menos para participar da #MeiadasCataratas\",\"datePublished\":\"2021-01-21T19:44:54+00:00\",\"dateModified\":\"2021-02-01T17:35:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/\"},\"wordCount\":376,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/\",\"name\":\"Moradores pagam menos para participar da #MeiadasCataratas - Blog Oficial do Marco das 3 Fronteiras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg\",\"datePublished\":\"2021-01-21T19:44:54+00:00\",\"dateModified\":\"2021-02-01T17:35:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg\",\"width\":2560,\"height\":1724},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/moradores-pagam-menos-para-participar-da-meiadascataratas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moradores pagam menos para participar da #MeiadasCataratas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/\",\"name\":\"Blog Oficial do Marco das 3 Fronteiras\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\",\"name\":\"Parques Rio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"caption\":\"Parques Rio\"},\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/author\\\/cataratas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moradores pagam menos para participar da #MeiadasCataratas - Blog Oficial do Marco das 3 Fronteiras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/","og_locale":"pt_BR","og_type":"article","og_title":"Moradores pagam menos para participar da #MeiadasCataratas - Blog Oficial do Marco das 3 Fronteiras","og_description":"As inscri\u00e7\u00f5es para a 13\u00aa edi\u00e7\u00e3o da Meia Maratona das Cataratas, uma das provas mais fascinantes do mundo, continuam abertas e com benef\u00edcios especiais aos habitantes das 14 cidades vizinhas ao Parque Nacional do Igua\u00e7u. Ao realizar a inscri\u00e7\u00e3o presencialmente, no Marco das 3 Fronteiras, o morador garante 20% de desconto. Cr\u00e9ditos fotografia: Nilton Rolin [&hellip;]","og_url":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/","og_site_name":"Blog Oficial do Marco das 3 Fronteiras","article_published_time":"2021-01-21T19:44:54+00:00","article_modified_time":"2021-02-01T17:35:16+00:00","og_image":[{"width":2560,"height":1724,"url":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg","type":"image\/jpeg"}],"author":"Parques Rio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Parques Rio","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/#article","isPartOf":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/"},"author":{"name":"Parques Rio","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba"},"headline":"Moradores pagam menos para participar da #MeiadasCataratas","datePublished":"2021-01-21T19:44:54+00:00","dateModified":"2021-02-01T17:35:16+00:00","mainEntityOfPage":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/"},"wordCount":376,"commentCount":0,"image":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/#primaryimage"},"thumbnailUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/","name":"Moradores pagam menos para participar da #MeiadasCataratas - Blog Oficial do Marco das 3 Fronteiras","isPartOf":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/#primaryimage"},"image":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/#primaryimage"},"thumbnailUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg","datePublished":"2021-01-21T19:44:54+00:00","dateModified":"2021-02-01T17:35:16+00:00","author":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba"},"breadcrumb":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/#primaryimage","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg","contentUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/01\/12-Meia-das-Cataratas-Foto-Marcos-Labanca-134-scaled.jpg","width":2560,"height":1724},{"@type":"BreadcrumbList","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/moradores-pagam-menos-para-participar-da-meiadascataratas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/marcodastresfronteiras.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Moradores pagam menos para participar da #MeiadasCataratas"}]},{"@type":"WebSite","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#website","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/","name":"Blog Oficial do Marco das 3 Fronteiras","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcodastresfronteiras.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba","name":"Parques Rio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","caption":"Parques Rio"},"url":"https:\/\/marcodastresfronteiras.com.br\/blog\/author\/cataratas\/"}]}},"_links":{"self":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts\/1240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1240"}],"version-history":[{"count":0,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts\/1240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/media\/1241"}],"wp:attachment":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}