{"id":1118,"date":"2020-12-11T11:15:12","date_gmt":"2020-12-11T14:15:12","guid":{"rendered":"https:\/\/marcodastresfronteiras.com.br\/blog\/?p=1118"},"modified":"2022-07-08T12:17:21","modified_gmt":"2022-07-08T15:17:21","slug":"a-viagem-gastronomica-do-marco-das-3-fronteiras","status":"publish","type":"post","link":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/","title":{"rendered":"A viagem gastron\u00f4mica do Marco das 3 Fronteiras"},"content":{"rendered":"<p style=\"text-align: justify;\">A viagem gastron\u00f4mica que o <a href=\"https:\/\/www.instagram.com\/marco3fronteiras\/\" target=\"_blank\" rel=\"noopener noreferrer\">Marco das 3 Fronteiras<\/a> oferece para os visitantes \u00e9 uma atra\u00e7\u00e3o a parte no local. Confira:<\/p>\n<p style=\"text-align: justify;\">O <a href=\"https:\/\/www.instagram.com\/restaurantecabezadevaca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Restaurante Cabeza de Vaca<\/a> possibilita uma viagem gastron\u00f4mica pela culin\u00e1ria regional, com uma vista singular da margem do Rio Igua\u00e7u, fronteira com a Argentina, e do Rio Paran\u00e1, que margeia a fronteira do Brasil com o Paraguai.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1135 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/marcos-300x200.jpg\" alt=\"\" width=\"572\" height=\"382\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/marcos-300x200.jpg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/marcos-768x512.jpg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/marcos.jpg 770w\" sizes=\"(max-width: 572px) 100vw, 572px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Foto: Marcos Labanca<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">No espa\u00e7o o visitante tem seus sentidos agu\u00e7ados, com o cen\u00e1rio, a gastronomia, o clima, as companhias e a energia que emana dos rios, das fronteiras e da mata. Colocar na programa\u00e7\u00e3o a visita ao restaurante \u00e9 vivenciar mais sensa\u00e7\u00f5es \u00fanicas nas Tr\u00eas Fronteiras. <strong>Confira o menu digital do Restaurante Cabeza de Vaca: <a href=\"https:\/\/drive.google.com\/file\/d\/12KdXyjnUqaxfGgo1Aey9wJq1GPVlNBmP\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\">https:\/\/drive.google.com\/file\/d\/12KdXyjnUqaxfGgo1Aey9wJq1GPVlNBmP\/view?usp=sharing<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">No restaurante voc\u00ea saboreia a culin\u00e1ria inspirada nos 3 pa\u00edses, como o prato inspirado no Brasil:<\/p>\n<p><img decoding=\"async\" class=\" wp-image-1272 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/02\/crditos-kiko-sierich_48642940677_o-300x200.jpg\" alt=\"\" width=\"575\" height=\"383\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/02\/crditos-kiko-sierich_48642940677_o-300x200.jpg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/02\/crditos-kiko-sierich_48642940677_o-1024x683.jpg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/02\/crditos-kiko-sierich_48642940677_o-768x512.jpg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/02\/crditos-kiko-sierich_48642940677_o-1536x1024.jpg 1536w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2021\/02\/crditos-kiko-sierich_48642940677_o-2048x1365.jpg 2048w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Kiko Siriech<\/span><\/em><\/p>\n<h3><strong>Picanha \u00e0 brasileira<\/strong><\/h3>\n<p style=\"text-align: justify;\">O prato brasileiro conta com saborosos fil\u00e9s de picanha em uma chapa quente. O visitante tem a oportunidade de selar a carne no ponto de sua prefer\u00eancia. O prato \u00e9 acompanhado de uma deliciosa farofa e batata crocante.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-1136 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/4-300x200.jpeg\" alt=\"\" width=\"575\" height=\"383\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/4-300x200.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/4-1024x682.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/4-768x512.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/4.jpeg 1280w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Nilton Rolin<\/span><\/em><\/p>\n<h3><strong>Contrafil\u00e9 argentino<\/strong><\/h3>\n<p style=\"text-align: justify;\">O prato inspirado nos sabores da argentina tem o cl\u00e1ssico bife de chorizo coberto com tempero chimichurri e vinagrete. A iguaria vem acompanhada por uma por\u00e7\u00e3o de arroz soltinho e farofa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1137 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/3-300x200.jpeg\" alt=\"\" width=\"573\" height=\"383\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/3-300x200.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/3-1024x682.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/3-768x512.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/3.jpeg 1280w\" sizes=\"(max-width: 573px) 100vw, 573px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Nilton Rolin<\/span><\/em><\/p>\n<h3><strong>Porco \u00e0 paraguaia<\/strong><\/h3>\n<p style=\"text-align: justify;\">A culin\u00e1ria do Paraguai pode ser saboreada com um delicioso porco \u00e0 pururuca. O prato tamb\u00e9m traz mandiocas cozidas, queijo derretido na cobertura, vinagrete e farofa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1150 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-11-at-11.21.21-300x200.jpeg\" alt=\"\" width=\"575\" height=\"383\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-11-at-11.21.21-300x200.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-11-at-11.21.21-1024x682.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-11-at-11.21.21-768x512.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-11-at-11.21.21.jpeg 1280w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Nilton Rolin<\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Na viagem gastron\u00f4mica do Marco o visitante ainda tem a oportunidade de experimentar sabores exclusivos que o atrativo proporciona, como \u00e9 o caso da cerveja Jaguarete.<\/p>\n<h3><strong>Cerveja Jaguarete<\/strong><\/h3>\n<p style=\"text-align: justify;\">Que tal uma cerveja geladinha e exclusiva do <a href=\"https:\/\/www.instagram.com\/restaurantecabezadevaca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Restaurante Cabeza de Vaca<\/a>? A cerveja possui um sabor marcante e saboroso e al\u00e9m de experimentar essa del\u00edcia, ao adquirir a cerveja o visitante colabora para a conserva\u00e7\u00e3o das on\u00e7as do Parque Nacional do Igua\u00e7u.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1140 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/10-225x300.jpeg\" alt=\"\" width=\"371\" height=\"492\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Wesner Ferreira<\/span><\/em><\/p>\n<h3><strong>Drinks Especiais<\/strong><\/h3>\n<p style=\"text-align: justify;\">No <a href=\"https:\/\/www.instagram.com\/restaurantecabezadevaca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Restaurante Cabeza de Vaca<\/a> voc\u00ea ainda encontra drinks e coquet\u00e9is especiais com sensa\u00e7\u00f5es e influ\u00eancias marcantes dos 3 pa\u00edses que formam a fronteira.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1131 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/cassiano-249x300.jpg\" alt=\"\" width=\"369\" height=\"445\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/cassiano-249x300.jpg 249w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/cassiano-850x1024.jpg 850w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/cassiano-768x926.jpg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/cassiano.jpg 945w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Cassiano Delapreve<\/span><\/em><\/p>\n<h3><strong>P\u00f4r do Sol<\/strong><\/h3>\n<p style=\"text-align: justify;\">No restaurante, al\u00e9m de viajar pelos sabores das 3 fronteiras, o visitante pode assistir ao p\u00f4r do sol latino do Marco. Uma paisagem deslumbrante que encanta a todos no deck do <a href=\"https:\/\/www.instagram.com\/restaurantecabezadevaca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Cabeza de Vaca<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1141 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/8-300x213.jpeg\" alt=\"\" width=\"574\" height=\"407\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/8-300x213.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/8-1024x726.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/8-768x544.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/8.jpeg 1280w\" sizes=\"(max-width: 574px) 100vw, 574px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Christian Rizzi<\/span><\/em><\/p>\n<h3><strong>M\u00fasica ao Vivo<\/strong><\/h3>\n<p style=\"text-align: justify;\">Toda a experi\u00eancia \u00e9 intensificada pela companhia de uma boa m\u00fasica ao vivo que envolve o visitante. A apresenta\u00e7\u00e3o acontece de ter\u00e7a a domingo, no deck do <a href=\"https:\/\/www.instagram.com\/restaurantecabezadevaca\/\" target=\"_blank\" rel=\"noopener noreferrer\">Restaurante Cabeza de Vaca<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1142 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/5-300x200.jpeg\" alt=\"\" width=\"574\" height=\"382\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/5-300x200.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/5-1024x682.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/5-768x512.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/5.jpeg 1280w\" sizes=\"(max-width: 574px) 100vw, 574px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Kiko Siriech<\/span><\/em><\/p>\n<h3><strong>Pra\u00e7a Gastron\u00f4mica das 3 Fronteiras<\/strong><\/h3>\n<p style=\"text-align: justify;\">A pra\u00e7a gastron\u00f4mica do Marco amplifica a experi\u00eancia do visitante e suas sensa\u00e7\u00f5es, conta com um card\u00e1pio especial da fronteira: tapioca, shawarma, churros, cachorro-quente, pipoca, caf\u00e9, chope, entre outras boas pedidas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1143 aligncenter\" src=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/9-300x200.jpeg\" alt=\"\" width=\"573\" height=\"382\" srcset=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/9-300x200.jpeg 300w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/9-1024x682.jpeg 1024w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/9-768x512.jpeg 768w, https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/9.jpeg 1280w\" sizes=\"(max-width: 573px) 100vw, 573px\" \/><\/p>\n<p style=\"text-align: center;\"><em><span style=\"font-size: 10pt;\">Fotografia: Christian Rizzi<\/span><\/em><\/p>\n<p><strong>Confira o menu digital do Restaurante Cabeza de Vaca: <a href=\"https:\/\/drive.google.com\/file\/d\/12KdXyjnUqaxfGgo1Aey9wJq1GPVlNBmP\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\">https:\/\/drive.google.com\/file\/d\/12KdXyjnUqaxfGgo1Aey9wJq1GPVlNBmP\/view?usp=sharing<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\">Visite o Marco e sinta a emo\u00e7\u00e3o de contemplar a gastronomia singular, toda a infraestrutura integrada \u00e0 natureza e \u00e0 paisagem local. Se tiver alguma d\u00favida ou quiser mandar um depoimento, pode entrar em contato e mandar mensagem no nosso n\u00famero de WhatsApp: 99137-3444 <span style=\"font-weight: 400;\">(<a href=\"http:\/\/wa.me\/554591373444\">wa.me\/554591373444<\/a>)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A viagem gastron\u00f4mica que o Marco das 3 Fronteiras oferece para os visitantes \u00e9 uma atra\u00e7\u00e3o a parte no local. Confira: O Restaurante Cabeza de Vaca possibilita uma viagem gastron\u00f4mica pela culin\u00e1ria regional, com uma vista singular da margem do Rio Igua\u00e7u, fronteira com a Argentina, e do Rio Paran\u00e1, que margeia a fronteira do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A viagem gastron\u00f4mica do Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A viagem gastron\u00f4mica do Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras\" \/>\n<meta property=\"og:description\" content=\"A viagem gastron\u00f4mica que o Marco das 3 Fronteiras oferece para os visitantes \u00e9 uma atra\u00e7\u00e3o a parte no local. Confira: O Restaurante Cabeza de Vaca possibilita uma viagem gastron\u00f4mica pela culin\u00e1ria regional, com uma vista singular da margem do Rio Igua\u00e7u, fronteira com a Argentina, e do Rio Paran\u00e1, que margeia a fronteira do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Oficial do Marco das 3 Fronteiras\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-11T14:15:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T15:17:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/7.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"851\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Parques Rio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Parques Rio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/\"},\"author\":{\"name\":\"Parques Rio\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\"},\"headline\":\"A viagem gastron\u00f4mica do Marco das 3 Fronteiras\",\"datePublished\":\"2020-12-11T14:15:12+00:00\",\"dateModified\":\"2022-07-08T15:17:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/\"},\"wordCount\":586,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/7.jpeg\",\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/\",\"name\":\"A viagem gastron\u00f4mica do Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/7.jpeg\",\"datePublished\":\"2020-12-11T14:15:12+00:00\",\"dateModified\":\"2022-07-08T15:17:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/7.jpeg\",\"contentUrl\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/7.jpeg\",\"width\":1280,\"height\":851},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/a-viagem-gastronomica-do-marco-das-3-fronteiras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A viagem gastron\u00f4mica do Marco das 3 Fronteiras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/\",\"name\":\"Blog Oficial do Marco das 3 Fronteiras\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/f5fcdd822e0183645f877899f3f084ba\",\"name\":\"Parques Rio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g\",\"caption\":\"Parques Rio\"},\"url\":\"https:\\\/\\\/marcodastresfronteiras.com.br\\\/blog\\\/author\\\/cataratas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A viagem gastron\u00f4mica do Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/","og_locale":"pt_BR","og_type":"article","og_title":"A viagem gastron\u00f4mica do Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras","og_description":"A viagem gastron\u00f4mica que o Marco das 3 Fronteiras oferece para os visitantes \u00e9 uma atra\u00e7\u00e3o a parte no local. Confira: O Restaurante Cabeza de Vaca possibilita uma viagem gastron\u00f4mica pela culin\u00e1ria regional, com uma vista singular da margem do Rio Igua\u00e7u, fronteira com a Argentina, e do Rio Paran\u00e1, que margeia a fronteira do [&hellip;]","og_url":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/","og_site_name":"Blog Oficial do Marco das 3 Fronteiras","article_published_time":"2020-12-11T14:15:12+00:00","article_modified_time":"2022-07-08T15:17:21+00:00","og_image":[{"width":1280,"height":851,"url":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/7.jpeg","type":"image\/jpeg"}],"author":"Parques Rio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Parques Rio","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/#article","isPartOf":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/"},"author":{"name":"Parques Rio","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba"},"headline":"A viagem gastron\u00f4mica do Marco das 3 Fronteiras","datePublished":"2020-12-11T14:15:12+00:00","dateModified":"2022-07-08T15:17:21+00:00","mainEntityOfPage":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/"},"wordCount":586,"commentCount":0,"image":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/#primaryimage"},"thumbnailUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/7.jpeg","inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/","name":"A viagem gastron\u00f4mica do Marco das 3 Fronteiras - Blog Oficial do Marco das 3 Fronteiras","isPartOf":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/#primaryimage"},"image":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/#primaryimage"},"thumbnailUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/7.jpeg","datePublished":"2020-12-11T14:15:12+00:00","dateModified":"2022-07-08T15:17:21+00:00","author":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba"},"breadcrumb":{"@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/#primaryimage","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/7.jpeg","contentUrl":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-content\/uploads\/2020\/12\/7.jpeg","width":1280,"height":851},{"@type":"BreadcrumbList","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/a-viagem-gastronomica-do-marco-das-3-fronteiras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/marcodastresfronteiras.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"A viagem gastron\u00f4mica do Marco das 3 Fronteiras"}]},{"@type":"WebSite","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#website","url":"https:\/\/marcodastresfronteiras.com.br\/blog\/","name":"Blog Oficial do Marco das 3 Fronteiras","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/marcodastresfronteiras.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/marcodastresfronteiras.com.br\/blog\/#\/schema\/person\/f5fcdd822e0183645f877899f3f084ba","name":"Parques Rio","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3377b708cc084f0a4b5ce764f005184daf61379e17dbd1de7a16e50ee63f2428?s=96&d=mm&r=g","caption":"Parques Rio"},"url":"https:\/\/marcodastresfronteiras.com.br\/blog\/author\/cataratas\/"}]}},"_links":{"self":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts\/1118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1118"}],"version-history":[{"count":0,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/posts\/1118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/media\/1144"}],"wp:attachment":[{"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marcodastresfronteiras.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}